{"id":15885,"date":"2023-09-01T16:16:29","date_gmt":"2023-09-01T14:16:29","guid":{"rendered":"https:\/\/www.trips-group.com\/?p=15885"},"modified":"2026-02-17T15:57:34","modified_gmt":"2026-02-17T14:57:34","slug":"trips-begruesst-neue-auszubildende-und-einen-dualen-studenten","status":"publish","type":"post","link":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/","title":{"rendered":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir starten mit gro\u00dfer Freude in den September, denn wir hei\u00dfen f\u00fcnf neue Auszubildende und einen Dualen Studenten in unseren Reihen herzlich willkommen. Dieser wichtige Schritt unterstreicht das Engagement f\u00fcr die Ausbildung junger Talente im Bereich der Elektronik und Automatisierungstechnik in der Region Mainfranken, dass das Gesch\u00e4fts- und Geschwisterduo Caroline und Christian Trips seit Jahrzehnten aktiv f\u00f6rdern und leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die neuen Auszubildenden werden den Beruf des&nbsp;<strong>Elektronikers&nbsp;<\/strong>(m\/w\/d)&nbsp;<strong>f\u00fcr Automatisierungstechnik<\/strong>&nbsp;erlernen, w\u00e4hrend der Duale Student eine spannende Reise im Bachelorstudiengang&nbsp;<strong>Elektro- und Informationstechnik (BET)<\/strong>&nbsp;in Kooperation mit der Technischen Hochschule W\u00fcrzburg-Schweinfurt (THWS) beginnt. Mit diesem Schritt setzen wir erneut auf die St\u00e4rkung von Nachwuchstalenten als Innovationsf\u00fchrer in der Branche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als TRIPS sind wir stolz auf unsere langj\u00e4hrige Tradition der Nachwuchsf\u00f6rderung. Neben zahlreichen unterj\u00e4hrlichen Aktionen wie dem Girls Day, der Teilnahme am MINT Tag, der RegioMainfranken Tour oder als Sponsor der Wissenswerkstatt in Schweinfurt, engagieren wir uns aktiv bei der SBIT (die j\u00e4hrliche Messe der Schweinfurter Berufsinformationstage auf der Maininsel) und setzen seit Jahrzehnten auf die Ausbildung im eigenen Haus f\u00fcr die Karrieren von Morgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr mehr Pr\u00e4senz im Bereich Ausbildung und Karrierem\u00f6glichkeiten haben wir k\u00fcrzlich eine interne und von Social Media begleitete Kampagne unter dem Motto \u201e#TRIPSteam \u2013 Strong together. Successful individually.\u201c gestartet. In w\u00f6chentlichen Beitr\u00e4gen auf den internen Kollaborationsplattform sowie auf den Social Media Kan\u00e4len zeigt die Firma von Caroline und Christian Trips inspirierende Karriereverl\u00e4ufe von Mitarbeitern, die bei TRIPS ihre Ausbildung begonnen haben. Diese Kampagne dient nicht nur dazu, die vielf\u00e4ltigen Karrierewege aufzuzeigen, die m\u00f6glich sind, sondern soll auch den aktuellen Auszubildenden Perspektiven f\u00fcr ihre eigene Zukunft bieten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eUnsere Auszubildenden sind der Motor f\u00fcr unsere Zukunft und Innovation\u201c, sagt Caroline Trips, Gesch\u00e4ftsf\u00fchrerin der TRIPS Group und IHK Pr\u00e4sidentin W\u00fcrzburg-Schweinfurt. \u201eMit der Integration neuer Talente in unser Team setzen wir nicht nur auf fachliche Weiterentwicklung, sondern f\u00f6rdern auch die pers\u00f6nliche Entwicklung und den Zusammenhalt innerhalb unseres Unternehmens.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TRIPS blickt auf eine erfolgreiche Unternehmensentwicklung zur\u00fcck und besch\u00e4ftigt mittlerweile mehr als 300 Mitarbeiter an vier Standorten. \u201eWir sind stolz darauf, eine vielf\u00e4ltige und wachsende Gemeinschaft zu sein, die Talente ausbildet, f\u00f6rdert und gemeinsam erfolgreich sein l\u00e4sst. Wir freuen uns auf eine erfolgreiche Zusammenarbeit mit unseren neuen Auszubildenden und dem Dualen Studenten und sind gespannt auf die frischen Ideen und Impulse, die sie in unser Unternehmen einbringen werden\u201c, so Christian Trips \u00fcber den Erfolg der eigenen Ausbildungswerkstatt mit dem bezeichnenden Titel \u201eIn charge of the future\u201c und die Verbundenheit des gesamten Teams zum Unternehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An alle Ausbildungsinteressierte f\u00fcr das Startlehrjahr 2024 gerichtet, bietet die TRIPS GmbH am&nbsp;<strong>Freitag, den 15.10.2023 von 15-18 Uhr<\/strong>&nbsp;einen&nbsp;<strong>Azubitag<\/strong>&nbsp;an, um sich ein erstes Bild zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ausbildungsangebot umfasst:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ausbildung zum Elektroniker (m\/w\/d) Automatisierungstechnik&nbsp;[Dauer: 3,5 Jahre]<\/li>\n\n\n\n<li>Ausbildung zum Industrieelektriker (m\/w\/d) Fachrichtung Betriebstechnik&nbsp;[Dauer: 2 Jahre]<\/li>\n\n\n\n<li>Duales Studium Elektro- und Informationstechnik<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Veranstaltung findet statt in der Zentrale, Hohe Heide 8-14 in Grafenrheinfeld statt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir starten mit gro\u00dfer Freude in den September, denn wir hei\u00dfen f\u00fcnf neue Auszubildende und einen Dualen Studenten in unseren Reihen herzlich willkommen. Dieser wichtige Schritt unterstreicht das Engagement f\u00fcr die Ausbildung junger Talente im Bereich der Elektronik und Automatisierungstechnik in&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"class_list":["post-15885","post","type-post","status-publish","format-standard","hentry","category-mitarbeiter"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Tilmann Bock\"\/>\n\t<meta name=\"msvalidate.01\" content=\"4B4AF3D76BB5A4999953F8D74930E999\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<meta name=\"msvalidate.01\" content=\"4B4AF3D76BB5A4999953F8D74930E999\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"TRIPS group - Process Automation I Digitization I Factory Automation\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group\" \/>\n\t\t<meta property=\"og:description\" content=\"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-01T14:16:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-17T14:57:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group\" \/>\n\t\t<meta name=\"twitter:description\" content=\"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#blogposting\",\"name\":\"TRIPS begr\\u00fc\\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group\",\"headline\":\"TRIPS begr\\u00fc\\u00dft neue Auszubildende und einen Dualen Studenten\",\"author\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/author\\\/tilmann-trips\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#organization\"},\"datePublished\":\"2023-09-01T16:16:29+02:00\",\"dateModified\":\"2026-02-17T15:57:34+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#webpage\"},\"articleSection\":\"Mitarbeiter, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/category\\\/mitarbeiter\\\/#listItem\",\"name\":\"Mitarbeiter\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/category\\\/mitarbeiter\\\/#listItem\",\"position\":2,\"name\":\"Mitarbeiter\",\"item\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/category\\\/mitarbeiter\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#listItem\",\"name\":\"TRIPS begr\\u00fc\\u00dft neue Auszubildende und einen Dualen Studenten\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#listItem\",\"position\":3,\"name\":\"TRIPS begr\\u00fc\\u00dft neue Auszubildende und einen Dualen Studenten\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/category\\\/mitarbeiter\\\/#listItem\",\"name\":\"Mitarbeiter\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#organization\",\"name\":\"TRIPS group\",\"description\":\"Process Automation I Digitization I Factory Automation\",\"url\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/author\\\/tilmann-trips\\\/#author\",\"url\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/author\\\/tilmann-trips\\\/\",\"name\":\"Tilmann Bock\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ae9437a9868eec91ae6f19ed1cbc273003ea85e35427777c20e26a9040a6b5a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Tilmann Bock\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#webpage\",\"url\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/\",\"name\":\"TRIPS begr\\u00fc\\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group\",\"description\":\"TRIPS, Spezialist f\\u00fcr Automatisierungsl\\u00f6sungen, freut sich \\u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/author\\\/tilmann-trips\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/author\\\/tilmann-trips\\\/#author\"},\"datePublished\":\"2023-09-01T16:16:29+02:00\",\"dateModified\":\"2026-02-17T15:57:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/\",\"name\":\"TRIPS group\",\"description\":\"Process Automation I Digitization I Factory Automation\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trips-group.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group","description":"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!","canonical_url":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"msvalidate.01":"4B4AF3D76BB5A4999953F8D74930E999","miscellaneous":"&lt;meta name=\"msvalidate.01\" content=\"4B4AF3D76BB5A4999953F8D74930E999\" \/&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#blogposting","name":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group","headline":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten","author":{"@id":"https:\/\/www.trips-group.com\/de\/author\/tilmann-trips\/#author"},"publisher":{"@id":"https:\/\/www.trips-group.com\/de\/#organization"},"datePublished":"2023-09-01T16:16:29+02:00","dateModified":"2026-02-17T15:57:34+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#webpage"},"isPartOf":{"@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#webpage"},"articleSection":"Mitarbeiter, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/www.trips-group.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/#listItem","name":"Mitarbeiter"}},{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/#listItem","position":2,"name":"Mitarbeiter","item":"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#listItem","name":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#listItem","position":3,"name":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten","previousItem":{"@type":"ListItem","@id":"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/#listItem","name":"Mitarbeiter"}}]},{"@type":"Organization","@id":"https:\/\/www.trips-group.com\/de\/#organization","name":"TRIPS group","description":"Process Automation I Digitization I Factory Automation","url":"https:\/\/www.trips-group.com\/de\/"},{"@type":"Person","@id":"https:\/\/www.trips-group.com\/de\/author\/tilmann-trips\/#author","url":"https:\/\/www.trips-group.com\/de\/author\/tilmann-trips\/","name":"Tilmann Bock","image":{"@type":"ImageObject","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8ae9437a9868eec91ae6f19ed1cbc273003ea85e35427777c20e26a9040a6b5a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Tilmann Bock"}},{"@type":"WebPage","@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#webpage","url":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/","name":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group","description":"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.trips-group.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/#breadcrumblist"},"author":{"@id":"https:\/\/www.trips-group.com\/de\/author\/tilmann-trips\/#author"},"creator":{"@id":"https:\/\/www.trips-group.com\/de\/author\/tilmann-trips\/#author"},"datePublished":"2023-09-01T16:16:29+02:00","dateModified":"2026-02-17T15:57:34+01:00"},{"@type":"WebSite","@id":"https:\/\/www.trips-group.com\/de\/#website","url":"https:\/\/www.trips-group.com\/de\/","name":"TRIPS group","description":"Process Automation I Digitization I Factory Automation","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.trips-group.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"TRIPS group - Process Automation I Digitization I Factory Automation","og:type":"article","og:title":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group","og:description":"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!","og:url":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/","article:published_time":"2023-09-01T14:16:29+00:00","article:modified_time":"2026-02-17T14:57:34+00:00","twitter:card":"summary_large_image","twitter:title":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten | TRIPS group","twitter:description":"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!"},"aioseo_meta_data":{"post_id":"15885","title":"#post_title | #site_title","description":"TRIPS, Spezialist f\u00fcr Automatisierungsl\u00f6sungen, freut sich \u00fcber neue Auszubildende und einen Dualen Studenten. Mehr lesen!","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-06-23 14:22:27","updated":"2026-02-17 15:04:15","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.trips-group.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/\" title=\"Mitarbeiter\">Mitarbeiter<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.trips-group.com\/de\/"},{"label":"Mitarbeiter","link":"https:\/\/www.trips-group.com\/de\/category\/mitarbeiter\/"},{"label":"TRIPS begr\u00fc\u00dft neue Auszubildende und einen Dualen Studenten","link":"https:\/\/www.trips-group.com\/de\/trips-begruesst-neue-auszubildende-und-einen-dualen-studenten\/"}],"_links":{"self":[{"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/posts\/15885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/comments?post=15885"}],"version-history":[{"count":2,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/posts\/15885\/revisions"}],"predecessor-version":[{"id":21360,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/posts\/15885\/revisions\/21360"}],"wp:attachment":[{"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/media?parent=15885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/categories?post=15885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trips-group.com\/de\/wp-json\/wp\/v2\/tags?post=15885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}